{"id":427999,"date":"2024-03-10T10:28:48","date_gmt":"2024-03-10T08:28:48","guid":{"rendered":"https:\/\/wmmaa.org\/islam-makhachev-reacciono-a-la-victoria-de-dustin-puryear-7\/"},"modified":"2024-03-10T10:28:48","modified_gmt":"2024-03-10T08:28:48","slug":"islam-makhachev-reacciono-a-la-victoria-de-dustin-puryear-7","status":"publish","type":"post","link":"https:\/\/wmmaa.org\/es\/islam-makhachev-reacciono-a-la-victoria-de-dustin-puryear-7\/","title":{"rendered":"Islam Makhachev reaccion\u00f3 a la victoria de Dustin Puryear"},"content":{"rendered":"<div id=\"feat-img-reg\" class=\"relative\">\n <img decoding=\"async\" src=\"https:\/\/wmmaa.org\/wp-content\/uploads\/2024\/03\/Islam-Makhachev-reacted-to-Dustin-Puryears-victory.jpg\" alt=\"Islam Makhachev reaccion\u00f3 a la victoria de Dustin Puryear\"><\/div>\n<div class=\"itemIntroText\">\n<p>El actual campe\u00f3n del peso ligero de la UFC y mejor luchador de la organizaci\u00f3n independientemente de la categor\u00eda de peso, Islam Makhachev, no pas\u00f3 por alto la exitosa actuaci\u00f3n de Dustin Puryear, que derrot\u00f3 al finalista franc\u00e9s Benoit Saint-Denis antes de tiempo en el UFC 299 celebrado en Miami.<\/p>\n<\/p>\n<\/div>\n<div class=\"itemFullText\">\n<blockquote>\n<p>\u00ab\u00a1Muy impresionante, Dustin!\u00bb, escribi\u00f3 el luchador ruso en las redes sociales, dirigi\u00e9ndose al estadounidense.<\/p>\n<\/blockquote>\n<p>La pelea de pesos ligeros entre Dustin Puryear y Beno Saint-Denis, que fue el segundo combate importante del evento numerado, termin\u00f3 en la marca de los 2:32 del segundo asalto con la victoria por nocaut de \u00abThe Diamond\u00bb. A la conclusi\u00f3n del torneo, ambos pesos ligeros recibieron 50.000 d\u00f3lares adicionales cada uno como participantes en \u00abFight of the Night\u00bb.<\/p>\n<p>Con su contundente victoria sobre el franc\u00e9s, el estadounidense no s\u00f3lo llam\u00f3 la atenci\u00f3n del campe\u00f3n, sino que conserv\u00f3 su tercer puesto en la clasificaci\u00f3n de la divisi\u00f3n.<\/p>\n<p>Recordemos que Islam Makhachev planea hacer otra defensa del cintur\u00f3n de campe\u00f3n en el verano de este a\u00f1o, pero la cuesti\u00f3n de su oponente sigue abierta.<\/p>\n<\/p>\n<\/div>\n<p class=\"source-link\">Fuente: https:\/\/fighttime.ru\/news\/item\/34138-islam-makhachev-otreagiroval-na-pobedu-dastina-pore.html?rand=19907<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actual campe\u00f3n del peso ligero de la UFC y mejor luchador de la organizaci\u00f3n independientemente de la categor\u00eda de peso, Islam Makhachev, no pas\u00f3 por alto la exitosa actuaci\u00f3n de Dustin Puryear, que derrot\u00f3 al finalista franc\u00e9s Benoit Saint-Denis antes de tiempo en el UFC 299 celebrado en Miami. \u00ab\u00a1Muy impresionante, Dustin!\u00bb, escribi\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171],"tags":[],"_links":{"self":[{"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/posts\/427999"}],"collection":[{"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/comments?post=427999"}],"version-history":[{"count":0,"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/posts\/427999\/revisions"}],"wp:attachment":[{"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/media?parent=427999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/categories?post=427999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wmmaa.org\/es\/wp-json\/wp\/v2\/tags?post=427999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}